{"id":9728,"date":"2024-06-19T11:58:32","date_gmt":"2024-06-19T11:58:32","guid":{"rendered":"https:\/\/simba.co.id\/?p=9728"},"modified":"2024-06-19T11:58:34","modified_gmt":"2024-06-19T11:58:34","slug":"tips-bonding-dengan-anak-saat-liburan-sekolah","status":"publish","type":"post","link":"https:\/\/simba.co.id\/eng\/tips-bonding-dengan-anak-saat-liburan-sekolah\/","title":{"rendered":"Tips Bonding dengan Anak Saat Liburan Sekolah"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":9729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-9728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parenting"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tips Bonding dengan Anak Saat Liburan Sekolah &#8212; Simba Cereal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/simba.co.id\/eng\/tips-bonding-dengan-anak-saat-liburan-sekolah\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tips Bonding dengan Anak Saat Liburan Sekolah &#8212; Simba Cereal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/simba.co.id\/eng\/tips-bonding-dengan-anak-saat-liburan-sekolah\/\" \/>\n<meta property=\"og:site_name\" content=\"Simba Cereal\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-19T11:58:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T11:58:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/simba.co.id\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrator\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/\"},\"author\":{\"name\":\"Administrator\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/#\\\/schema\\\/person\\\/4a3482c48bbb755f37501634806b5590\"},\"headline\":\"Tips Bonding dengan Anak Saat Liburan Sekolah\",\"datePublished\":\"2024-06-19T11:58:32+00:00\",\"dateModified\":\"2024-06-19T11:58:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/\"},\"wordCount\":7,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg\",\"articleSection\":[\"Parenting\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/\",\"url\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/\",\"name\":\"Tips Bonding dengan Anak Saat Liburan Sekolah &#8212; Simba Cereal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg\",\"datePublished\":\"2024-06-19T11:58:32+00:00\",\"dateModified\":\"2024-06-19T11:58:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg\",\"contentUrl\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/tips-bonding-dengan-anak-saat-liburan-sekolah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/simba.co.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips Bonding dengan Anak Saat Liburan Sekolah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/#website\",\"url\":\"https:\\\/\\\/simba.co.id\\\/\",\"name\":\"Simba Cereal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/#organization\"},\"alternateName\":\"Simba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/simba.co.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/#organization\",\"name\":\"PT Simba Indosnack Makmur\",\"alternateName\":\"Simba\",\"url\":\"https:\\\/\\\/simba.co.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-simba-1.png\",\"contentUrl\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-simba-1.png\",\"width\":512,\"height\":512,\"caption\":\"PT Simba Indosnack Makmur\"},\"image\":{\"@id\":\"https:\\\/\\\/simba.co.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.tiktok.com\\\/@simbacerealofficial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/#\\\/schema\\\/person\\\/4a3482c48bbb755f37501634806b5590\",\"name\":\"Administrator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/litespeed\\\/avatar\\\/b1912bde51e640ed473db906ce4e4830.jpg?ver=1787889604\",\"url\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/litespeed\\\/avatar\\\/b1912bde51e640ed473db906ce4e4830.jpg?ver=1787889604\",\"contentUrl\":\"https:\\\/\\\/simba.co.id\\\/wp-content\\\/litespeed\\\/avatar\\\/b1912bde51e640ed473db906ce4e4830.jpg?ver=1787889604\",\"caption\":\"Administrator\"},\"sameAs\":[\"http:\\\/\\\/localhost\\\/simba\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tips Bonding dengan Anak Saat Liburan Sekolah &#8212; Simba Cereal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/simba.co.id\/eng\/tips-bonding-dengan-anak-saat-liburan-sekolah\/","og_locale":"en_GB","og_type":"article","og_title":"Tips Bonding dengan Anak Saat Liburan Sekolah &#8212; Simba Cereal","og_url":"https:\/\/simba.co.id\/eng\/tips-bonding-dengan-anak-saat-liburan-sekolah\/","og_site_name":"Simba Cereal","article_published_time":"2024-06-19T11:58:32+00:00","article_modified_time":"2024-06-19T11:58:34+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/simba.co.id\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg","type":"image\/jpeg"}],"author":"Administrator","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Administrator"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/#article","isPartOf":{"@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/"},"author":{"name":"Administrator","@id":"https:\/\/simba.co.id\/#\/schema\/person\/4a3482c48bbb755f37501634806b5590"},"headline":"Tips Bonding dengan Anak Saat Liburan Sekolah","datePublished":"2024-06-19T11:58:32+00:00","dateModified":"2024-06-19T11:58:34+00:00","mainEntityOfPage":{"@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/"},"wordCount":7,"commentCount":0,"publisher":{"@id":"https:\/\/simba.co.id\/#organization"},"image":{"@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/#primaryimage"},"thumbnailUrl":"https:\/\/simba.co.id\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg","articleSection":["Parenting"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/","url":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/","name":"Tips Bonding dengan Anak Saat Liburan Sekolah &#8212; Simba Cereal","isPartOf":{"@id":"https:\/\/simba.co.id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/#primaryimage"},"image":{"@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/#primaryimage"},"thumbnailUrl":"https:\/\/simba.co.id\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg","datePublished":"2024-06-19T11:58:32+00:00","dateModified":"2024-06-19T11:58:34+00:00","breadcrumb":{"@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/#primaryimage","url":"https:\/\/simba.co.id\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg","contentUrl":"https:\/\/simba.co.id\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-19-at-03.40.02.jpeg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/simba.co.id\/tips-bonding-dengan-anak-saat-liburan-sekolah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/simba.co.id\/"},{"@type":"ListItem","position":2,"name":"Tips Bonding dengan Anak Saat Liburan Sekolah"}]},{"@type":"WebSite","@id":"https:\/\/simba.co.id\/#website","url":"https:\/\/simba.co.id\/","name":"Simba Cereal","description":"","publisher":{"@id":"https:\/\/simba.co.id\/#organization"},"alternateName":"Simba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/simba.co.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/simba.co.id\/#organization","name":"PT Simba Indosnack Makmur","alternateName":"Simba","url":"https:\/\/simba.co.id\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/simba.co.id\/#\/schema\/logo\/image\/","url":"https:\/\/simba.co.id\/wp-content\/uploads\/2023\/07\/logo-simba-1.png","contentUrl":"https:\/\/simba.co.id\/wp-content\/uploads\/2023\/07\/logo-simba-1.png","width":512,"height":512,"caption":"PT Simba Indosnack Makmur"},"image":{"@id":"https:\/\/simba.co.id\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.tiktok.com\/@simbacerealofficial\/"]},{"@type":"Person","@id":"https:\/\/simba.co.id\/#\/schema\/person\/4a3482c48bbb755f37501634806b5590","name":"Administrator","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/simba.co.id\/wp-content\/litespeed\/avatar\/b1912bde51e640ed473db906ce4e4830.jpg?ver=1787889604","url":"https:\/\/simba.co.id\/wp-content\/litespeed\/avatar\/b1912bde51e640ed473db906ce4e4830.jpg?ver=1787889604","contentUrl":"https:\/\/simba.co.id\/wp-content\/litespeed\/avatar\/b1912bde51e640ed473db906ce4e4830.jpg?ver=1787889604","caption":"Administrator"},"sameAs":["http:\/\/localhost\/simba"]}]}},"_links":{"self":[{"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/posts\/9728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/comments?post=9728"}],"version-history":[{"count":3,"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/posts\/9728\/revisions"}],"predecessor-version":[{"id":9737,"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/posts\/9728\/revisions\/9737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/media\/9729"}],"wp:attachment":[{"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/media?parent=9728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/categories?post=9728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simba.co.id\/eng\/wp-json\/wp\/v2\/tags?post=9728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}